{"id":16,"count":2,"description":"","link":"https:\/\/careergarden.jp\/kokuzeisenmonkan\/recruit-cat\/","name":"\u5c31\u8077\u30fb\u8ee2\u8077","slug":"recruit-cat","taxonomy":"category","parent":0,"meta":[],"acf":{"supervisor":null},"_links":{"self":[{"href":"https:\/\/careergarden.jp\/kokuzeisenmonkan\/wp-json\/wp\/v2\/categories\/16"}],"collection":[{"href":"https:\/\/careergarden.jp\/kokuzeisenmonkan\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/careergarden.jp\/kokuzeisenmonkan\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/careergarden.jp\/kokuzeisenmonkan\/wp-json\/wp\/v2\/posts?categories=16"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}